{"id":20212,"date":"2017-09-30T16:49:33","date_gmt":"2017-09-30T16:49:33","guid":{"rendered":"https:\/\/www.navarroaubanell.com\/producto\/shine-6\/"},"modified":"2020-03-16T12:46:50","modified_gmt":"2020-03-16T11:46:50","slug":"shine-6","status":"publish","type":"product","link":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/","title":{"rendered":"Tamboret Shine"},"content":{"rendered":"<p>Realitzat totalment en alumini, el tamboret Shine de Arik Levy es presenta elegant i vers\u00e0til, apta per a nombrosos contextos tant en el sector residencial com en hostaleria i restauraci\u00f3. L&#8217;\u00fas de l&#8217;alumini fa que sigui extremadament lleugera, funcional i molt resistent als agents atmosf\u00e8rics, per tant tamb\u00e9 apta per a les zones costaneres. Shine \u00e9s una col\u00b7lecci\u00f3 completa, pensada per a la decoraci\u00f3 de zones de menjador i de relax.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":30529,"template":"","meta":{"_acf_changed":false},"product_brand":[890],"product_cat":[563,574],"product_tag":[587,816,618,636,847,720,745,872],"class_list":{"0":"post-20212","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-emu-ca","7":"product_cat-exterior-ca","8":"product_cat-tamborets-exterior","9":"product_tag-apilable-ca","10":"product_tag-chill-out-ca","11":"product_tag-contract-ca","12":"product_tag-emu-ca","13":"product_tag-mobiliari-exterior","14":"product_tag-outdoor-ca","15":"product_tag-shine-ca","16":"product_tag-tamborets-exterior","17":"description-off","19":"first","20":"instock","21":"shipping-taxable","22":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tamburet per a exterior Shine, de la firma Emu - Navarro Aubanell<\/title>\n<meta name=\"description\" content=\"Realitzat totalment en alumini, el tamboret Shine de Arik Levy es presenta elegant i vers\u00e0til, apta per a nombrosos contextos, restauraci\u00f3 o resid\u00e8ncies.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tamburet per a exterior Shine, de la firma Emu - Navarro Aubanell\" \/>\n<meta property=\"og:description\" content=\"Realitzat totalment en alumini, el tamboret Shine de Arik Levy es presenta elegant i vers\u00e0til, apta per a nombrosos contextos, restauraci\u00f3 o resid\u00e8ncies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Navarro Aubanell\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-16T11:46:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.navarroaubanell.com\/wp-content\/uploads\/2017\/09\/img-destacad_shine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/producte\\\/shine-6\\\/\",\"url\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/producte\\\/shine-6\\\/\",\"name\":\"Tamburet per a exterior Shine, de la firma Emu - Navarro Aubanell\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/producte\\\/shine-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/producte\\\/shine-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.navarroaubanell.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/img-destacad_shine.jpg\",\"datePublished\":\"2017-09-30T16:49:33+00:00\",\"dateModified\":\"2020-03-16T11:46:50+00:00\",\"description\":\"Realitzat totalment en alumini, el tamboret Shine de Arik Levy es presenta elegant i vers\u00e0til, apta per a nombrosos contextos, restauraci\u00f3 o resid\u00e8ncies.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/producte\\\/shine-6\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/producte\\\/shine-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/producte\\\/shine-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.navarroaubanell.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/img-destacad_shine.jpg\",\"contentUrl\":\"https:\\\/\\\/www.navarroaubanell.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/img-destacad_shine.jpg\",\"width\":800,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/producte\\\/shine-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productes\",\"item\":\"https:\\\/\\\/www.navarroaubanell.com\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tamboret Shine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/\",\"name\":\"Navarro Aubanell\",\"description\":\"Mobiliario para hoteler\u00eda, colectividades y oficinas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/#organization\",\"name\":\"COMERCIAL NAVARRO AUBANELL, S.A\",\"url\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.navarroaubanell.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/logo-navarro-aubuanell.png\",\"contentUrl\":\"https:\\\/\\\/www.navarroaubanell.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/logo-navarro-aubuanell.png\",\"width\":6304,\"height\":1154,\"caption\":\"COMERCIAL NAVARRO AUBANELL, S.A\"},\"image\":{\"@id\":\"https:\\\/\\\/www.navarroaubanell.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tamburet per a exterior Shine, de la firma Emu - Navarro Aubanell","description":"Realitzat totalment en alumini, el tamboret Shine de Arik Levy es presenta elegant i vers\u00e0til, apta per a nombrosos contextos, restauraci\u00f3 o resid\u00e8ncies.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/","og_locale":"ca_ES","og_type":"article","og_title":"Tamburet per a exterior Shine, de la firma Emu - Navarro Aubanell","og_description":"Realitzat totalment en alumini, el tamboret Shine de Arik Levy es presenta elegant i vers\u00e0til, apta per a nombrosos contextos, restauraci\u00f3 o resid\u00e8ncies.","og_url":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/","og_site_name":"Navarro Aubanell","article_modified_time":"2020-03-16T11:46:50+00:00","og_image":[{"width":800,"height":650,"url":"https:\/\/www.navarroaubanell.com\/wp-content\/uploads\/2017\/09\/img-destacad_shine.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/","url":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/","name":"Tamburet per a exterior Shine, de la firma Emu - Navarro Aubanell","isPartOf":{"@id":"https:\/\/www.navarroaubanell.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/#primaryimage"},"image":{"@id":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/#primaryimage"},"thumbnailUrl":"https:\/\/www.navarroaubanell.com\/wp-content\/uploads\/2017\/09\/img-destacad_shine.jpg","datePublished":"2017-09-30T16:49:33+00:00","dateModified":"2020-03-16T11:46:50+00:00","description":"Realitzat totalment en alumini, el tamboret Shine de Arik Levy es presenta elegant i vers\u00e0til, apta per a nombrosos contextos, restauraci\u00f3 o resid\u00e8ncies.","breadcrumb":{"@id":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/#primaryimage","url":"https:\/\/www.navarroaubanell.com\/wp-content\/uploads\/2017\/09\/img-destacad_shine.jpg","contentUrl":"https:\/\/www.navarroaubanell.com\/wp-content\/uploads\/2017\/09\/img-destacad_shine.jpg","width":800,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/www.navarroaubanell.com\/ca\/producte\/shine-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.navarroaubanell.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Productes","item":"https:\/\/www.navarroaubanell.com\/productos\/"},{"@type":"ListItem","position":3,"name":"Tamboret Shine"}]},{"@type":"WebSite","@id":"https:\/\/www.navarroaubanell.com\/ca\/#website","url":"https:\/\/www.navarroaubanell.com\/ca\/","name":"Navarro Aubanell","description":"Mobiliario para hoteler\u00eda, colectividades y oficinas","publisher":{"@id":"https:\/\/www.navarroaubanell.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.navarroaubanell.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.navarroaubanell.com\/ca\/#organization","name":"COMERCIAL NAVARRO AUBANELL, S.A","url":"https:\/\/www.navarroaubanell.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.navarroaubanell.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.navarroaubanell.com\/wp-content\/uploads\/2017\/07\/logo-navarro-aubuanell.png","contentUrl":"https:\/\/www.navarroaubanell.com\/wp-content\/uploads\/2017\/07\/logo-navarro-aubuanell.png","width":6304,"height":1154,"caption":"COMERCIAL NAVARRO AUBANELL, S.A"},"image":{"@id":"https:\/\/www.navarroaubanell.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.navarroaubanell.com\/ca\/wp-json\/wp\/v2\/product\/20212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.navarroaubanell.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.navarroaubanell.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.navarroaubanell.com\/ca\/wp-json\/wp\/v2\/media\/30529"}],"wp:attachment":[{"href":"https:\/\/www.navarroaubanell.com\/ca\/wp-json\/wp\/v2\/media?parent=20212"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.navarroaubanell.com\/ca\/wp-json\/wp\/v2\/product_brand?post=20212"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.navarroaubanell.com\/ca\/wp-json\/wp\/v2\/product_cat?post=20212"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.navarroaubanell.com\/ca\/wp-json\/wp\/v2\/product_tag?post=20212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}